{"id":187,"date":"2024-01-22T11:51:57","date_gmt":"2024-01-22T10:51:57","guid":{"rendered":"https:\/\/nodesmarket.com\/?page_id=187"},"modified":"2026-06-23T12:16:57","modified_gmt":"2026-06-23T10:16:57","slug":"meet-the-team","status":"publish","type":"page","link":"https:\/\/nodesmarket.com\/no\/meet-the-team\/","title":{"rendered":"Meet the Team"},"content":{"rendered":"\n<h1 class=\"wp-block-heading has-text-align-center\">Meet the Team<\/h1>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\">NODES\u2122 has a highly experienced team with diverse backgrounds in information technology, electricity markets, regulation, grid operation, project management, and customer support<\/p>\n\n\n\n<div class=\"wp-block-group alignwide has-global-padding is-layout-constrained wp-block-group-is-layout-constrained\" style=\"padding-top:var(--wp--preset--spacing--60);padding-bottom:var(--wp--preset--spacing--60)\">\n<h2 class=\"wp-block-heading has-text-align-center\" style=\"margin-bottom:var(--wp--preset--spacing--50)\">Core Team<\/h2>\n\n\n\n<div class=\"wp-block-group alignwide is-style-grid-cols-auto-fill\/min:17rem is-nowrap is-layout-flex wp-container-core-group-is-layout-9ad21752 wp-block-group-is-layout-flex\">\n<div class=\"wp-block-site-person-card\" id=\"block-f1c92815fe38d3d391a66374912046b3\">\n\n<div class=\"wp-block-site-person-card__inner\">\n\t<div class=\"wp-block-site-person-card__figure\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"582\" src=\"https:\/\/ds7yx6kld6i0w.cloudfront.net\/wp-content\/uploads\/2024\/02\/15111708\/Richard-Sarti-e1733907145423-1024x582.jpg\" class=\"wp-block-site-person-card__image\" alt=\"\" srcset=\"https:\/\/ds7yx6kld6i0w.cloudfront.net\/wp-content\/uploads\/2024\/02\/15111708\/Richard-Sarti-e1733907145423-1024x582.jpg 1024w, https:\/\/ds7yx6kld6i0w.cloudfront.net\/wp-content\/uploads\/2024\/02\/15111708\/Richard-Sarti-e1733907145423-300x170.jpg 300w, https:\/\/ds7yx6kld6i0w.cloudfront.net\/wp-content\/uploads\/2024\/02\/15111708\/Richard-Sarti-e1733907145423-768x436.jpg 768w, https:\/\/ds7yx6kld6i0w.cloudfront.net\/wp-content\/uploads\/2024\/02\/15111708\/Richard-Sarti-e1733907145423-1536x872.jpg 1536w, https:\/\/ds7yx6kld6i0w.cloudfront.net\/wp-content\/uploads\/2024\/02\/15111708\/Richard-Sarti-e1733907145423-2048x1163.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/>\t\t\t<\/div>\n\t<div class=\"wp-block-site-person-card__body\">\n\t\t<h3 class=\"wp-block-site-person-card__name\">\n\t\t\tRichard Sarti\t\t<\/h3>\n\t\t<div class=\"wp-block-site-person-card__title\">\n\t\t\tCEO\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"wp-block-site-person-card__linked-in\">\n\t\t\t\t<span class=\"wp-block-site-person-card__sr-only\">LinkedIn profil:<\/span>\n\t\t\t\t<a class=\"wp-block-site-person-card__linked-in-link\" href=\"https:\/\/www.linkedin.com\/in\/richard-sarti-67293b4\/\" target=\"_blank\" rel=\"nofollow\">\n\t\t\t\t\t<img\n\t\t\t\t\t\tdecoding=\"async\"\n\t\t\t\t\t\talt=\"LinkedIn\"\n\t\t\t\t\t\tsrc=\"https:\/\/nodesmarket.com\/wp-content\/plugins\/site\/\/blocks\/person-card\/LinkedIn.png\"\n\t\t\t\t\t\twidth=\"2212\"\n\t\t\t\t\t\theight=\"540\"\n\t\t\t\t\t\tclass=\"wp-block-site-person-card__linked-in-img\"\n\t\t\t\t\t\/>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t<\/div>\n<\/div>\n\n<\/div>\n\n\n\n<div class=\"wp-block-site-person-card\" id=\"block-7a2507ccfc5eaf3c1cc25ffd6666272e\">\n\n<div class=\"wp-block-site-person-card__inner\">\n\t<div class=\"wp-block-site-person-card__figure\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"729\" height=\"1000\" src=\"https:\/\/ds7yx6kld6i0w.cloudfront.net\/wp-content\/uploads\/2026\/06\/23121647\/aa8f276c-eb9a-48a2-8018-40ece1380240.jpg\" class=\"wp-block-site-person-card__image\" alt=\"\" srcset=\"https:\/\/ds7yx6kld6i0w.cloudfront.net\/wp-content\/uploads\/2026\/06\/23121647\/aa8f276c-eb9a-48a2-8018-40ece1380240.jpg 729w, https:\/\/ds7yx6kld6i0w.cloudfront.net\/wp-content\/uploads\/2026\/06\/23121647\/aa8f276c-eb9a-48a2-8018-40ece1380240-219x300.jpg 219w\" sizes=\"auto, (max-width: 729px) 100vw, 729px\" \/>\t\t\t<\/div>\n\t<div class=\"wp-block-site-person-card__body\">\n\t\t<h3 class=\"wp-block-site-person-card__name\">\n\t\t\tSvein J\u00f8rgen S\u00f8nning\t\t<\/h3>\n\t\t<div class=\"wp-block-site-person-card__title\">\n\t\t\tCCTO\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"wp-block-site-person-card__linked-in\">\n\t\t\t\t<span class=\"wp-block-site-person-card__sr-only\">LinkedIn profil:<\/span>\n\t\t\t\t<a class=\"wp-block-site-person-card__linked-in-link\" href=\"https:\/\/www.linkedin.com\/in\/sjsinnovation\/\" target=\"_blank\" rel=\"nofollow\">\n\t\t\t\t\t<img\n\t\t\t\t\t\tdecoding=\"async\"\n\t\t\t\t\t\talt=\"LinkedIn\"\n\t\t\t\t\t\tsrc=\"https:\/\/nodesmarket.com\/wp-content\/plugins\/site\/\/blocks\/person-card\/LinkedIn.png\"\n\t\t\t\t\t\twidth=\"2212\"\n\t\t\t\t\t\theight=\"540\"\n\t\t\t\t\t\tclass=\"wp-block-site-person-card__linked-in-img\"\n\t\t\t\t\t\/>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t<\/div>\n<\/div>\n\n<\/div>\n\n\n\n<div class=\"wp-block-site-person-card\" id=\"block-735506f6f68f19c589b561da25a43518\">\n\n<div class=\"wp-block-site-person-card__inner\">\n\t<div class=\"wp-block-site-person-card__figure\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/ds7yx6kld6i0w.cloudfront.net\/wp-content\/uploads\/2024\/02\/15111713\/Sofia-Eng-1024x683.jpg\" class=\"wp-block-site-person-card__image\" alt=\"\" srcset=\"https:\/\/ds7yx6kld6i0w.cloudfront.net\/wp-content\/uploads\/2024\/02\/15111713\/Sofia-Eng-1024x683.jpg 1024w, https:\/\/ds7yx6kld6i0w.cloudfront.net\/wp-content\/uploads\/2024\/02\/15111713\/Sofia-Eng-300x200.jpg 300w, https:\/\/ds7yx6kld6i0w.cloudfront.net\/wp-content\/uploads\/2024\/02\/15111713\/Sofia-Eng-768x512.jpg 768w, https:\/\/ds7yx6kld6i0w.cloudfront.net\/wp-content\/uploads\/2024\/02\/15111713\/Sofia-Eng-1536x1024.jpg 1536w, https:\/\/ds7yx6kld6i0w.cloudfront.net\/wp-content\/uploads\/2024\/02\/15111713\/Sofia-Eng-2048x1366.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/>\t\t\t<\/div>\n\t<div class=\"wp-block-site-person-card__body\">\n\t\t<h3 class=\"wp-block-site-person-card__name\">\n\t\t\tSofia Eng\t\t<\/h3>\n\t\t<div class=\"wp-block-site-person-card__title\">\n\t\t\tHead of Markets and Operations\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"wp-block-site-person-card__linked-in\">\n\t\t\t\t<span class=\"wp-block-site-person-card__sr-only\">LinkedIn profil:<\/span>\n\t\t\t\t<a class=\"wp-block-site-person-card__linked-in-link\" href=\"https:\/\/www.linkedin.com\/in\/9276065\/\" target=\"_blank\" rel=\"nofollow\">\n\t\t\t\t\t<img\n\t\t\t\t\t\tdecoding=\"async\"\n\t\t\t\t\t\talt=\"LinkedIn\"\n\t\t\t\t\t\tsrc=\"https:\/\/nodesmarket.com\/wp-content\/plugins\/site\/\/blocks\/person-card\/LinkedIn.png\"\n\t\t\t\t\t\twidth=\"2212\"\n\t\t\t\t\t\theight=\"540\"\n\t\t\t\t\t\tclass=\"wp-block-site-person-card__linked-in-img\"\n\t\t\t\t\t\/>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t<\/div>\n<\/div>\n\n<\/div>\n\n\n\n<div class=\"wp-block-site-person-card\" id=\"block-500fb75e6d19dfb3b6206ce57a6053f2\">\n\n<div class=\"wp-block-site-person-card__inner\">\n\t<div class=\"wp-block-site-person-card__figure\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"480\" src=\"https:\/\/ds7yx6kld6i0w.cloudfront.net\/wp-content\/uploads\/2024\/01\/30160635\/Henrik.-Carlsen.jpeg\" class=\"wp-block-site-person-card__image\" alt=\"\" srcset=\"https:\/\/ds7yx6kld6i0w.cloudfront.net\/wp-content\/uploads\/2024\/01\/30160635\/Henrik.-Carlsen.jpeg 640w, https:\/\/ds7yx6kld6i0w.cloudfront.net\/wp-content\/uploads\/2024\/01\/30160635\/Henrik.-Carlsen-300x225.jpeg 300w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/>\t\t\t<\/div>\n\t<div class=\"wp-block-site-person-card__body\">\n\t\t<h3 class=\"wp-block-site-person-card__name\">\n\t\t\tHenrik Carlsen\t\t<\/h3>\n\t\t<div class=\"wp-block-site-person-card__title\">\n\t\t\tHead of Finance \t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"wp-block-site-person-card__linked-in\">\n\t\t\t\t<span class=\"wp-block-site-person-card__sr-only\">LinkedIn profil:<\/span>\n\t\t\t\t<a class=\"wp-block-site-person-card__linked-in-link\" href=\"https:\/\/www.linkedin.com\/in\/hcarlsen\/\" target=\"_blank\" rel=\"nofollow\">\n\t\t\t\t\t<img\n\t\t\t\t\t\tdecoding=\"async\"\n\t\t\t\t\t\talt=\"LinkedIn\"\n\t\t\t\t\t\tsrc=\"https:\/\/nodesmarket.com\/wp-content\/plugins\/site\/\/blocks\/person-card\/LinkedIn.png\"\n\t\t\t\t\t\twidth=\"2212\"\n\t\t\t\t\t\theight=\"540\"\n\t\t\t\t\t\tclass=\"wp-block-site-person-card__linked-in-img\"\n\t\t\t\t\t\/>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t<\/div>\n<\/div>\n\n<\/div>\n\n\n\n<div class=\"wp-block-site-person-card\" id=\"block-23fc9a3bdebd9ac62b75ccfb7197ede6\">\n\n<div class=\"wp-block-site-person-card__inner\">\n\t<div class=\"wp-block-site-person-card__figure\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"901\" src=\"https:\/\/ds7yx6kld6i0w.cloudfront.net\/wp-content\/uploads\/2024\/02\/15111651\/HALLSTEIN-HAGEN-e1733907067130-1024x901.jpeg\" class=\"wp-block-site-person-card__image\" alt=\"\" srcset=\"https:\/\/ds7yx6kld6i0w.cloudfront.net\/wp-content\/uploads\/2024\/02\/15111651\/HALLSTEIN-HAGEN-e1733907067130-1024x901.jpeg 1024w, https:\/\/ds7yx6kld6i0w.cloudfront.net\/wp-content\/uploads\/2024\/02\/15111651\/HALLSTEIN-HAGEN-e1733907067130-300x264.jpeg 300w, https:\/\/ds7yx6kld6i0w.cloudfront.net\/wp-content\/uploads\/2024\/02\/15111651\/HALLSTEIN-HAGEN-e1733907067130-768x676.jpeg 768w, https:\/\/ds7yx6kld6i0w.cloudfront.net\/wp-content\/uploads\/2024\/02\/15111651\/HALLSTEIN-HAGEN-e1733907067130-1536x1351.jpeg 1536w, https:\/\/ds7yx6kld6i0w.cloudfront.net\/wp-content\/uploads\/2024\/02\/15111651\/HALLSTEIN-HAGEN-e1733907067130-2048x1801.jpeg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/>\t\t\t<\/div>\n\t<div class=\"wp-block-site-person-card__body\">\n\t\t<h3 class=\"wp-block-site-person-card__name\">\n\t\t\tHallstein Hagen\t\t<\/h3>\n\t\t<div class=\"wp-block-site-person-card__title\">\n\t\t\tSenior Consultant\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"wp-block-site-person-card__linked-in\">\n\t\t\t\t<span class=\"wp-block-site-person-card__sr-only\">LinkedIn profil:<\/span>\n\t\t\t\t<a class=\"wp-block-site-person-card__linked-in-link\" href=\"https:\/\/www.linkedin.com\/in\/hallstein-hagen\" target=\"_blank\" rel=\"nofollow\">\n\t\t\t\t\t<img\n\t\t\t\t\t\tdecoding=\"async\"\n\t\t\t\t\t\talt=\"LinkedIn\"\n\t\t\t\t\t\tsrc=\"https:\/\/nodesmarket.com\/wp-content\/plugins\/site\/\/blocks\/person-card\/LinkedIn.png\"\n\t\t\t\t\t\twidth=\"2212\"\n\t\t\t\t\t\theight=\"540\"\n\t\t\t\t\t\tclass=\"wp-block-site-person-card__linked-in-img\"\n\t\t\t\t\t\/>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t<\/div>\n<\/div>\n\n<\/div>\n\n\n\n<div class=\"wp-block-site-person-card\" id=\"block-60986c1c35c4f9e958c16d34e779371f\">\n\n<div class=\"wp-block-site-person-card__inner\">\n\t<div class=\"wp-block-site-person-card__figure\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"958\" height=\"1024\" src=\"https:\/\/ds7yx6kld6i0w.cloudfront.net\/wp-content\/uploads\/2024\/02\/15111638\/Farhan-Farrukh-e1733907104917-958x1024.jpeg\" class=\"wp-block-site-person-card__image\" alt=\"\" srcset=\"https:\/\/ds7yx6kld6i0w.cloudfront.net\/wp-content\/uploads\/2024\/02\/15111638\/Farhan-Farrukh-e1733907104917-958x1024.jpeg 958w, https:\/\/ds7yx6kld6i0w.cloudfront.net\/wp-content\/uploads\/2024\/02\/15111638\/Farhan-Farrukh-e1733907104917-281x300.jpeg 281w, https:\/\/ds7yx6kld6i0w.cloudfront.net\/wp-content\/uploads\/2024\/02\/15111638\/Farhan-Farrukh-e1733907104917-768x821.jpeg 768w, https:\/\/ds7yx6kld6i0w.cloudfront.net\/wp-content\/uploads\/2024\/02\/15111638\/Farhan-Farrukh-e1733907104917-1437x1536.jpeg 1437w, https:\/\/ds7yx6kld6i0w.cloudfront.net\/wp-content\/uploads\/2024\/02\/15111638\/Farhan-Farrukh-e1733907104917-1916x2048.jpeg 1916w, https:\/\/ds7yx6kld6i0w.cloudfront.net\/wp-content\/uploads\/2024\/02\/15111638\/Farhan-Farrukh-e1733907104917.jpeg 1920w\" sizes=\"auto, (max-width: 958px) 100vw, 958px\" \/>\t\t\t<\/div>\n\t<div class=\"wp-block-site-person-card__body\">\n\t\t<h3 class=\"wp-block-site-person-card__name\">\n\t\t\tFarhan Farrukh\t\t<\/h3>\n\t\t<div class=\"wp-block-site-person-card__title\">\n\t\t\tBusiness Development Manager\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"wp-block-site-person-card__linked-in\">\n\t\t\t\t<span class=\"wp-block-site-person-card__sr-only\">LinkedIn profil:<\/span>\n\t\t\t\t<a class=\"wp-block-site-person-card__linked-in-link\" href=\"https:\/\/www.linkedin.com\/in\/farhan--farrukh\/\" target=\"_blank\" rel=\"nofollow\">\n\t\t\t\t\t<img\n\t\t\t\t\t\tdecoding=\"async\"\n\t\t\t\t\t\talt=\"LinkedIn\"\n\t\t\t\t\t\tsrc=\"https:\/\/nodesmarket.com\/wp-content\/plugins\/site\/\/blocks\/person-card\/LinkedIn.png\"\n\t\t\t\t\t\twidth=\"2212\"\n\t\t\t\t\t\theight=\"540\"\n\t\t\t\t\t\tclass=\"wp-block-site-person-card__linked-in-img\"\n\t\t\t\t\t\/>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t<\/div>\n<\/div>\n\n<\/div>\n\n\n\n<div class=\"wp-block-site-person-card\" id=\"block-e96b291c01a1eaa825b358457664080d\">\n\n<div class=\"wp-block-site-person-card__inner\">\n\t<div class=\"wp-block-site-person-card__figure\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/ds7yx6kld6i0w.cloudfront.net\/wp-content\/uploads\/2024\/01\/22152816\/anders-staude.jpg\" class=\"wp-block-site-person-card__image\" alt=\"\" srcset=\"https:\/\/ds7yx6kld6i0w.cloudfront.net\/wp-content\/uploads\/2024\/01\/22152816\/anders-staude.jpg 400w, https:\/\/ds7yx6kld6i0w.cloudfront.net\/wp-content\/uploads\/2024\/01\/22152816\/anders-staude-300x300.jpg 300w, https:\/\/ds7yx6kld6i0w.cloudfront.net\/wp-content\/uploads\/2024\/01\/22152816\/anders-staude-150x150.jpg 150w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>\t\t\t<\/div>\n\t<div class=\"wp-block-site-person-card__body\">\n\t\t<h3 class=\"wp-block-site-person-card__name\">\n\t\t\tAnders Staude\t\t<\/h3>\n\t\t<div class=\"wp-block-site-person-card__title\">\n\t\t\tSenior Project Manager\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"wp-block-site-person-card__linked-in\">\n\t\t\t\t<span class=\"wp-block-site-person-card__sr-only\">LinkedIn profil:<\/span>\n\t\t\t\t<a class=\"wp-block-site-person-card__linked-in-link\" href=\"https:\/\/www.linkedin.com\/in\/anders-staude-344258126\/\" target=\"_blank\" rel=\"nofollow\">\n\t\t\t\t\t<img\n\t\t\t\t\t\tdecoding=\"async\"\n\t\t\t\t\t\talt=\"LinkedIn\"\n\t\t\t\t\t\tsrc=\"https:\/\/nodesmarket.com\/wp-content\/plugins\/site\/\/blocks\/person-card\/LinkedIn.png\"\n\t\t\t\t\t\twidth=\"2212\"\n\t\t\t\t\t\theight=\"540\"\n\t\t\t\t\t\tclass=\"wp-block-site-person-card__linked-in-img\"\n\t\t\t\t\t\/>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t<\/div>\n<\/div>\n\n<\/div>\n\n\n\n<div class=\"wp-block-site-person-card\" id=\"block-e94800bf51dfff8c985ef7ce984aa57a\">\n\n<div class=\"wp-block-site-person-card__inner\">\n\t<div class=\"wp-block-site-person-card__figure\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/ds7yx6kld6i0w.cloudfront.net\/wp-content\/uploads\/2024\/02\/15111631\/Daniel-Stolsbotn-1024x683.jpeg\" class=\"wp-block-site-person-card__image\" alt=\"\" srcset=\"https:\/\/ds7yx6kld6i0w.cloudfront.net\/wp-content\/uploads\/2024\/02\/15111631\/Daniel-Stolsbotn-1024x683.jpeg 1024w, https:\/\/ds7yx6kld6i0w.cloudfront.net\/wp-content\/uploads\/2024\/02\/15111631\/Daniel-Stolsbotn-300x200.jpeg 300w, https:\/\/ds7yx6kld6i0w.cloudfront.net\/wp-content\/uploads\/2024\/02\/15111631\/Daniel-Stolsbotn-768x512.jpeg 768w, https:\/\/ds7yx6kld6i0w.cloudfront.net\/wp-content\/uploads\/2024\/02\/15111631\/Daniel-Stolsbotn-1536x1024.jpeg 1536w, https:\/\/ds7yx6kld6i0w.cloudfront.net\/wp-content\/uploads\/2024\/02\/15111631\/Daniel-Stolsbotn-2048x1366.jpeg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/>\t\t\t<\/div>\n\t<div class=\"wp-block-site-person-card__body\">\n\t\t<h3 class=\"wp-block-site-person-card__name\">\n\t\t\tDaniel St\u00f8lsbotn\t\t<\/h3>\n\t\t<div class=\"wp-block-site-person-card__title\">\n\t\t\tSenior Project Manager &amp; Operations Manager\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"wp-block-site-person-card__linked-in\">\n\t\t\t\t<span class=\"wp-block-site-person-card__sr-only\">LinkedIn profil:<\/span>\n\t\t\t\t<a class=\"wp-block-site-person-card__linked-in-link\" href=\"https:\/\/www.linkedin.com\/in\/daniel-st%C3%B8lsbotn-a2b631a1\/\" target=\"_blank\" rel=\"nofollow\">\n\t\t\t\t\t<img\n\t\t\t\t\t\tdecoding=\"async\"\n\t\t\t\t\t\talt=\"LinkedIn\"\n\t\t\t\t\t\tsrc=\"https:\/\/nodesmarket.com\/wp-content\/plugins\/site\/\/blocks\/person-card\/LinkedIn.png\"\n\t\t\t\t\t\twidth=\"2212\"\n\t\t\t\t\t\theight=\"540\"\n\t\t\t\t\t\tclass=\"wp-block-site-person-card__linked-in-img\"\n\t\t\t\t\t\/>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t<\/div>\n<\/div>\n\n<\/div>\n\n\n\n<div class=\"wp-block-site-person-card\" id=\"block-fa05dfa3bd27ff4c6ce34f9daae9fdc8\">\n\n<div class=\"wp-block-site-person-card__inner\">\n\t<div class=\"wp-block-site-person-card__figure\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/ds7yx6kld6i0w.cloudfront.net\/wp-content\/uploads\/2024\/02\/15111643\/Guro-Grotterud-768x1024.jpeg\" class=\"wp-block-site-person-card__image\" alt=\"\" srcset=\"https:\/\/ds7yx6kld6i0w.cloudfront.net\/wp-content\/uploads\/2024\/02\/15111643\/Guro-Grotterud-768x1024.jpeg 768w, https:\/\/ds7yx6kld6i0w.cloudfront.net\/wp-content\/uploads\/2024\/02\/15111643\/Guro-Grotterud-225x300.jpeg 225w, https:\/\/ds7yx6kld6i0w.cloudfront.net\/wp-content\/uploads\/2024\/02\/15111643\/Guro-Grotterud-1152x1536.jpeg 1152w, https:\/\/ds7yx6kld6i0w.cloudfront.net\/wp-content\/uploads\/2024\/02\/15111643\/Guro-Grotterud-1536x2048.jpeg 1536w, https:\/\/ds7yx6kld6i0w.cloudfront.net\/wp-content\/uploads\/2024\/02\/15111643\/Guro-Grotterud.jpeg 1920w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/>\t\t\t<\/div>\n\t<div class=\"wp-block-site-person-card__body\">\n\t\t<h3 class=\"wp-block-site-person-card__name\">\n\t\t\tGuro Gr\u00f8tterud\t\t<\/h3>\n\t\t<div class=\"wp-block-site-person-card__title\">\n\t\t\tDirector Regulatory Affairs \/ Senior Project Manager\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"wp-block-site-person-card__linked-in\">\n\t\t\t\t<span class=\"wp-block-site-person-card__sr-only\">LinkedIn profil:<\/span>\n\t\t\t\t<a class=\"wp-block-site-person-card__linked-in-link\" href=\"https:\/\/www.linkedin.com\/in\/guro-grotterud\/\" target=\"_blank\" rel=\"nofollow\">\n\t\t\t\t\t<img\n\t\t\t\t\t\tdecoding=\"async\"\n\t\t\t\t\t\talt=\"LinkedIn\"\n\t\t\t\t\t\tsrc=\"https:\/\/nodesmarket.com\/wp-content\/plugins\/site\/\/blocks\/person-card\/LinkedIn.png\"\n\t\t\t\t\t\twidth=\"2212\"\n\t\t\t\t\t\theight=\"540\"\n\t\t\t\t\t\tclass=\"wp-block-site-person-card__linked-in-img\"\n\t\t\t\t\t\/>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t<\/div>\n<\/div>\n\n<\/div>\n\n\n\n<div class=\"wp-block-site-person-card\" id=\"block-29c96fdb065686cb67ae4d0e8c260152\">\n\n<div class=\"wp-block-site-person-card__inner\">\n\t<div class=\"wp-block-site-person-card__figure\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/ds7yx6kld6i0w.cloudfront.net\/wp-content\/uploads\/2024\/02\/15111038\/Fotograf_Nicki_Twang_W3A6732-1024x683.jpg\" class=\"wp-block-site-person-card__image\" alt=\"\" srcset=\"https:\/\/ds7yx6kld6i0w.cloudfront.net\/wp-content\/uploads\/2024\/02\/15111038\/Fotograf_Nicki_Twang_W3A6732-1024x683.jpg 1024w, https:\/\/ds7yx6kld6i0w.cloudfront.net\/wp-content\/uploads\/2024\/02\/15111038\/Fotograf_Nicki_Twang_W3A6732-300x200.jpg 300w, https:\/\/ds7yx6kld6i0w.cloudfront.net\/wp-content\/uploads\/2024\/02\/15111038\/Fotograf_Nicki_Twang_W3A6732-768x512.jpg 768w, https:\/\/ds7yx6kld6i0w.cloudfront.net\/wp-content\/uploads\/2024\/02\/15111038\/Fotograf_Nicki_Twang_W3A6732-1536x1024.jpg 1536w, https:\/\/ds7yx6kld6i0w.cloudfront.net\/wp-content\/uploads\/2024\/02\/15111038\/Fotograf_Nicki_Twang_W3A6732-2048x1366.jpg 2048w, https:\/\/ds7yx6kld6i0w.cloudfront.net\/wp-content\/uploads\/2024\/02\/15111038\/Fotograf_Nicki_Twang_W3A6732-e1707992101146.jpg 600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/>\t\t\t<\/div>\n\t<div class=\"wp-block-site-person-card__body\">\n\t\t<h3 class=\"wp-block-site-person-card__name\">\n\t\t\tGesa Milzer\t\t<\/h3>\n\t\t<div class=\"wp-block-site-person-card__title\">\n\t\t\tSenior Project Manager\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"wp-block-site-person-card__linked-in\">\n\t\t\t\t<span class=\"wp-block-site-person-card__sr-only\">LinkedIn profil:<\/span>\n\t\t\t\t<a class=\"wp-block-site-person-card__linked-in-link\" href=\"https:\/\/www.linkedin.com\/in\/gesa-milzer-5ba46657\/\" target=\"_blank\" rel=\"nofollow\">\n\t\t\t\t\t<img\n\t\t\t\t\t\tdecoding=\"async\"\n\t\t\t\t\t\talt=\"LinkedIn\"\n\t\t\t\t\t\tsrc=\"https:\/\/nodesmarket.com\/wp-content\/plugins\/site\/\/blocks\/person-card\/LinkedIn.png\"\n\t\t\t\t\t\twidth=\"2212\"\n\t\t\t\t\t\theight=\"540\"\n\t\t\t\t\t\tclass=\"wp-block-site-person-card__linked-in-img\"\n\t\t\t\t\t\/>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t<\/div>\n<\/div>\n\n<\/div>\n\n\n\n<div class=\"wp-block-site-person-card\" id=\"block-e6c69eb8449908d93b50ef350313a440\">\n\n<div class=\"wp-block-site-person-card__inner\">\n\t<div class=\"wp-block-site-person-card__figure\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/ds7yx6kld6i0w.cloudfront.net\/wp-content\/uploads\/2024\/02\/15111705\/Oystein-Dyvik-Eide.jpeg\" class=\"wp-block-site-person-card__image\" alt=\"\" srcset=\"https:\/\/ds7yx6kld6i0w.cloudfront.net\/wp-content\/uploads\/2024\/02\/15111705\/Oystein-Dyvik-Eide.jpeg 400w, https:\/\/ds7yx6kld6i0w.cloudfront.net\/wp-content\/uploads\/2024\/02\/15111705\/Oystein-Dyvik-Eide-300x300.jpeg 300w, https:\/\/ds7yx6kld6i0w.cloudfront.net\/wp-content\/uploads\/2024\/02\/15111705\/Oystein-Dyvik-Eide-150x150.jpeg 150w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>\t\t\t<\/div>\n\t<div class=\"wp-block-site-person-card__body\">\n\t\t<h3 class=\"wp-block-site-person-card__name\">\n\t\t\t\u00d8ystein Dyvik Eide\t\t<\/h3>\n\t\t<div class=\"wp-block-site-person-card__title\">\n\t\t\tHead of Products\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"wp-block-site-person-card__linked-in\">\n\t\t\t\t<span class=\"wp-block-site-person-card__sr-only\">LinkedIn profil:<\/span>\n\t\t\t\t<a class=\"wp-block-site-person-card__linked-in-link\" href=\"https:\/\/www.linkedin.com\/in\/oystein-eide\/\" target=\"_blank\" rel=\"nofollow\">\n\t\t\t\t\t<img\n\t\t\t\t\t\tdecoding=\"async\"\n\t\t\t\t\t\talt=\"LinkedIn\"\n\t\t\t\t\t\tsrc=\"https:\/\/nodesmarket.com\/wp-content\/plugins\/site\/\/blocks\/person-card\/LinkedIn.png\"\n\t\t\t\t\t\twidth=\"2212\"\n\t\t\t\t\t\theight=\"540\"\n\t\t\t\t\t\tclass=\"wp-block-site-person-card__linked-in-img\"\n\t\t\t\t\t\/>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t<\/div>\n<\/div>\n\n<\/div>\n\n\n\n<div class=\"wp-block-site-person-card\" id=\"block-33350e9f9465b30ffeb121023c749e40\">\n\n<div class=\"wp-block-site-person-card__inner\">\n\t<div class=\"wp-block-site-person-card__figure\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"700\" height=\"700\" src=\"https:\/\/ds7yx6kld6i0w.cloudfront.net\/wp-content\/uploads\/2024\/02\/15113851\/Jorge-Rodriguez-Vecino.jpg\" class=\"wp-block-site-person-card__image\" alt=\"\" srcset=\"https:\/\/ds7yx6kld6i0w.cloudfront.net\/wp-content\/uploads\/2024\/02\/15113851\/Jorge-Rodriguez-Vecino.jpg 700w, https:\/\/ds7yx6kld6i0w.cloudfront.net\/wp-content\/uploads\/2024\/02\/15113851\/Jorge-Rodriguez-Vecino-300x300.jpg 300w, https:\/\/ds7yx6kld6i0w.cloudfront.net\/wp-content\/uploads\/2024\/02\/15113851\/Jorge-Rodriguez-Vecino-150x150.jpg 150w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/>\t\t\t<\/div>\n\t<div class=\"wp-block-site-person-card__body\">\n\t\t<h3 class=\"wp-block-site-person-card__name\">\n\t\t\tJorge Rodriguez Vecino\t\t<\/h3>\n\t\t<div class=\"wp-block-site-person-card__title\">\n\t\t\tTech Lead\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"wp-block-site-person-card__linked-in\">\n\t\t\t\t<span class=\"wp-block-site-person-card__sr-only\">LinkedIn profil:<\/span>\n\t\t\t\t<a class=\"wp-block-site-person-card__linked-in-link\" href=\"https:\/\/www.linkedin.com\/in\/jorgerodriguez827\/\" target=\"_blank\" rel=\"nofollow\">\n\t\t\t\t\t<img\n\t\t\t\t\t\tdecoding=\"async\"\n\t\t\t\t\t\talt=\"LinkedIn\"\n\t\t\t\t\t\tsrc=\"https:\/\/nodesmarket.com\/wp-content\/plugins\/site\/\/blocks\/person-card\/LinkedIn.png\"\n\t\t\t\t\t\twidth=\"2212\"\n\t\t\t\t\t\theight=\"540\"\n\t\t\t\t\t\tclass=\"wp-block-site-person-card__linked-in-img\"\n\t\t\t\t\t\/>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t<\/div>\n<\/div>\n\n<\/div>\n\n\n\n<div class=\"wp-block-site-person-card\" id=\"block-07a82fd52194103e7f0c71929f66db44\">\n\n<div class=\"wp-block-site-person-card__inner\">\n\t<div class=\"wp-block-site-person-card__figure\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"950\" height=\"1024\" src=\"https:\/\/ds7yx6kld6i0w.cloudfront.net\/wp-content\/uploads\/2024\/02\/20110454\/Jan-Helge-e1733907027427-950x1024.jpg\" class=\"wp-block-site-person-card__image\" alt=\"\" srcset=\"https:\/\/ds7yx6kld6i0w.cloudfront.net\/wp-content\/uploads\/2024\/02\/20110454\/Jan-Helge-e1733907027427-950x1024.jpg 950w, https:\/\/ds7yx6kld6i0w.cloudfront.net\/wp-content\/uploads\/2024\/02\/20110454\/Jan-Helge-e1733907027427-278x300.jpg 278w, https:\/\/ds7yx6kld6i0w.cloudfront.net\/wp-content\/uploads\/2024\/02\/20110454\/Jan-Helge-e1733907027427-768x828.jpg 768w, https:\/\/ds7yx6kld6i0w.cloudfront.net\/wp-content\/uploads\/2024\/02\/20110454\/Jan-Helge-e1733907027427.jpg 978w\" sizes=\"auto, (max-width: 950px) 100vw, 950px\" \/>\t\t\t<\/div>\n\t<div class=\"wp-block-site-person-card__body\">\n\t\t<h3 class=\"wp-block-site-person-card__name\">\n\t\t\tJan Helge Helgesen\t\t<\/h3>\n\t\t<div class=\"wp-block-site-person-card__title\">\n\t\t\tFull-stack Developer\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"wp-block-site-person-card__linked-in\">\n\t\t\t\t<span class=\"wp-block-site-person-card__sr-only\">LinkedIn profil:<\/span>\n\t\t\t\t<a class=\"wp-block-site-person-card__linked-in-link\" href=\"https:\/\/www.linkedin.com\/in\/jan-helge-helgesen-155207152\/\" target=\"_blank\" rel=\"nofollow\">\n\t\t\t\t\t<img\n\t\t\t\t\t\tdecoding=\"async\"\n\t\t\t\t\t\talt=\"LinkedIn\"\n\t\t\t\t\t\tsrc=\"https:\/\/nodesmarket.com\/wp-content\/plugins\/site\/\/blocks\/person-card\/LinkedIn.png\"\n\t\t\t\t\t\twidth=\"2212\"\n\t\t\t\t\t\theight=\"540\"\n\t\t\t\t\t\tclass=\"wp-block-site-person-card__linked-in-img\"\n\t\t\t\t\t\/>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t<\/div>\n<\/div>\n\n<\/div>\n\n\n\n<div class=\"wp-block-site-person-card\" id=\"block-f1c671c1a06ef231ca80a65fbc142b26\">\n\n<div class=\"wp-block-site-person-card__inner\">\n\t<div class=\"wp-block-site-person-card__figure\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"899\" height=\"1024\" src=\"https:\/\/ds7yx6kld6i0w.cloudfront.net\/wp-content\/uploads\/2024\/02\/11145915\/Atle-Wandsvik-e1733906977174-899x1024.jpeg\" class=\"wp-block-site-person-card__image\" alt=\"\" srcset=\"https:\/\/ds7yx6kld6i0w.cloudfront.net\/wp-content\/uploads\/2024\/02\/11145915\/Atle-Wandsvik-e1733906977174-899x1024.jpeg 899w, https:\/\/ds7yx6kld6i0w.cloudfront.net\/wp-content\/uploads\/2024\/02\/11145915\/Atle-Wandsvik-e1733906977174-263x300.jpeg 263w, https:\/\/ds7yx6kld6i0w.cloudfront.net\/wp-content\/uploads\/2024\/02\/11145915\/Atle-Wandsvik-e1733906977174-768x875.jpeg 768w, https:\/\/ds7yx6kld6i0w.cloudfront.net\/wp-content\/uploads\/2024\/02\/11145915\/Atle-Wandsvik-e1733906977174-1348x1536.jpeg 1348w, https:\/\/ds7yx6kld6i0w.cloudfront.net\/wp-content\/uploads\/2024\/02\/11145915\/Atle-Wandsvik-e1733906977174-1797x2048.jpeg 1797w, https:\/\/ds7yx6kld6i0w.cloudfront.net\/wp-content\/uploads\/2024\/02\/11145915\/Atle-Wandsvik-e1733906977174.jpeg 1920w\" sizes=\"auto, (max-width: 899px) 100vw, 899px\" \/>\t\t\t<\/div>\n\t<div class=\"wp-block-site-person-card__body\">\n\t\t<h3 class=\"wp-block-site-person-card__name\">\n\t\t\tAtle Wandsvik\t\t<\/h3>\n\t\t<div class=\"wp-block-site-person-card__title\">\n\t\t\tData &amp; System Lead\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"wp-block-site-person-card__linked-in\">\n\t\t\t\t<span class=\"wp-block-site-person-card__sr-only\">LinkedIn profil:<\/span>\n\t\t\t\t<a class=\"wp-block-site-person-card__linked-in-link\" href=\"https:\/\/www.linkedin.com\/in\/atle-wandsvik\/\" target=\"_blank\" rel=\"nofollow\">\n\t\t\t\t\t<img\n\t\t\t\t\t\tdecoding=\"async\"\n\t\t\t\t\t\talt=\"LinkedIn\"\n\t\t\t\t\t\tsrc=\"https:\/\/nodesmarket.com\/wp-content\/plugins\/site\/\/blocks\/person-card\/LinkedIn.png\"\n\t\t\t\t\t\twidth=\"2212\"\n\t\t\t\t\t\theight=\"540\"\n\t\t\t\t\t\tclass=\"wp-block-site-person-card__linked-in-img\"\n\t\t\t\t\t\/>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t<\/div>\n<\/div>\n\n<\/div>\n\n\n\n<div class=\"wp-block-site-person-card\" id=\"block-b887cc6bfcb44a577975ba1d98e0a274\">\n\n<div class=\"wp-block-site-person-card__inner\">\n\t<div class=\"wp-block-site-person-card__figure\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/ds7yx6kld6i0w.cloudfront.net\/wp-content\/uploads\/2024\/08\/19124105\/20220709_180423-1024x1024.jpg\" class=\"wp-block-site-person-card__image\" alt=\"\" srcset=\"https:\/\/ds7yx6kld6i0w.cloudfront.net\/wp-content\/uploads\/2024\/08\/19124105\/20220709_180423-1024x1024.jpg 1024w, https:\/\/ds7yx6kld6i0w.cloudfront.net\/wp-content\/uploads\/2024\/08\/19124105\/20220709_180423-300x300.jpg 300w, https:\/\/ds7yx6kld6i0w.cloudfront.net\/wp-content\/uploads\/2024\/08\/19124105\/20220709_180423-150x150.jpg 150w, https:\/\/ds7yx6kld6i0w.cloudfront.net\/wp-content\/uploads\/2024\/08\/19124105\/20220709_180423-768x767.jpg 768w, https:\/\/ds7yx6kld6i0w.cloudfront.net\/wp-content\/uploads\/2024\/08\/19124105\/20220709_180423.jpg 1447w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/>\t\t\t<\/div>\n\t<div class=\"wp-block-site-person-card__body\">\n\t\t<h3 class=\"wp-block-site-person-card__name\">\n\t\t\tMadeeha Kahn\t\t<\/h3>\n\t\t<div class=\"wp-block-site-person-card__title\">\n\t\t\tDevSecOps Lead\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"wp-block-site-person-card__linked-in\">\n\t\t\t\t<span class=\"wp-block-site-person-card__sr-only\">LinkedIn profil:<\/span>\n\t\t\t\t<a class=\"wp-block-site-person-card__linked-in-link\" href=\"https:\/\/www.linkedin.com\/in\/madeehakhan28\/\" target=\"_blank\" rel=\"nofollow\">\n\t\t\t\t\t<img\n\t\t\t\t\t\tdecoding=\"async\"\n\t\t\t\t\t\talt=\"LinkedIn\"\n\t\t\t\t\t\tsrc=\"https:\/\/nodesmarket.com\/wp-content\/plugins\/site\/\/blocks\/person-card\/LinkedIn.png\"\n\t\t\t\t\t\twidth=\"2212\"\n\t\t\t\t\t\theight=\"540\"\n\t\t\t\t\t\tclass=\"wp-block-site-person-card__linked-in-img\"\n\t\t\t\t\t\/>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t<\/div>\n<\/div>\n\n<\/div>\n\n\n\n<div class=\"wp-block-site-person-card\" id=\"block-717a726c3164ad410933bf09e628b714\">\n\n<div class=\"wp-block-site-person-card__inner\">\n\t<div class=\"wp-block-site-person-card__figure\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"729\" height=\"642\" src=\"https:\/\/ds7yx6kld6i0w.cloudfront.net\/wp-content\/uploads\/2024\/10\/29142428\/Image-e1733906950748.jpg\" class=\"wp-block-site-person-card__image\" alt=\"\" srcset=\"https:\/\/ds7yx6kld6i0w.cloudfront.net\/wp-content\/uploads\/2024\/10\/29142428\/Image-e1733906950748.jpg 729w, https:\/\/ds7yx6kld6i0w.cloudfront.net\/wp-content\/uploads\/2024\/10\/29142428\/Image-e1733906950748-300x264.jpg 300w\" sizes=\"auto, (max-width: 729px) 100vw, 729px\" \/>\t\t\t<\/div>\n\t<div class=\"wp-block-site-person-card__body\">\n\t\t<h3 class=\"wp-block-site-person-card__name\">\n\t\t\tBenjamin Holsten\t\t<\/h3>\n\t\t<div class=\"wp-block-site-person-card__title\">\n\t\t\tBusiness Development Manager\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"wp-block-site-person-card__linked-in\">\n\t\t\t\t<span class=\"wp-block-site-person-card__sr-only\">LinkedIn profil:<\/span>\n\t\t\t\t<a class=\"wp-block-site-person-card__linked-in-link\" href=\"https:\/\/www.linkedin.com\/in\/benjamin-holsten-bb8a13103\/\" target=\"_blank\" rel=\"nofollow\">\n\t\t\t\t\t<img\n\t\t\t\t\t\tdecoding=\"async\"\n\t\t\t\t\t\talt=\"LinkedIn\"\n\t\t\t\t\t\tsrc=\"https:\/\/nodesmarket.com\/wp-content\/plugins\/site\/\/blocks\/person-card\/LinkedIn.png\"\n\t\t\t\t\t\twidth=\"2212\"\n\t\t\t\t\t\theight=\"540\"\n\t\t\t\t\t\tclass=\"wp-block-site-person-card__linked-in-img\"\n\t\t\t\t\t\/>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t<\/div>\n<\/div>\n\n<\/div>\n\n\n\n<div class=\"wp-block-site-person-card\" id=\"block-a1bbb0641bc2d31a0698825775743f60\">\n\n<div class=\"wp-block-site-person-card__inner\">\n\t<div class=\"wp-block-site-person-card__figure\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"627\" height=\"1024\" src=\"https:\/\/ds7yx6kld6i0w.cloudfront.net\/wp-content\/uploads\/2025\/01\/28093311\/IMG_5304-627x1024.jpg\" class=\"wp-block-site-person-card__image\" alt=\"\" srcset=\"https:\/\/ds7yx6kld6i0w.cloudfront.net\/wp-content\/uploads\/2025\/01\/28093311\/IMG_5304-627x1024.jpg 627w, https:\/\/ds7yx6kld6i0w.cloudfront.net\/wp-content\/uploads\/2025\/01\/28093311\/IMG_5304-184x300.jpg 184w, https:\/\/ds7yx6kld6i0w.cloudfront.net\/wp-content\/uploads\/2025\/01\/28093311\/IMG_5304-768x1254.jpg 768w, https:\/\/ds7yx6kld6i0w.cloudfront.net\/wp-content\/uploads\/2025\/01\/28093311\/IMG_5304-941x1536.jpg 941w, https:\/\/ds7yx6kld6i0w.cloudfront.net\/wp-content\/uploads\/2025\/01\/28093311\/IMG_5304-1254x2048.jpg 1254w, https:\/\/ds7yx6kld6i0w.cloudfront.net\/wp-content\/uploads\/2025\/01\/28093311\/IMG_5304.jpg 1568w\" sizes=\"auto, (max-width: 627px) 100vw, 627px\" \/>\t\t\t<\/div>\n\t<div class=\"wp-block-site-person-card__body\">\n\t\t<h3 class=\"wp-block-site-person-card__name\">\n\t\t\tSanjay Kumar Rahul\t\t<\/h3>\n\t\t<div class=\"wp-block-site-person-card__title\">\n\t\t\tFull-stack Developer\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"wp-block-site-person-card__linked-in\">\n\t\t\t\t<span class=\"wp-block-site-person-card__sr-only\">LinkedIn profil:<\/span>\n\t\t\t\t<a class=\"wp-block-site-person-card__linked-in-link\" href=\"https:\/\/www.linkedin.com\/in\/sanjaykumarrahul\/\" target=\"_blank\" rel=\"nofollow\">\n\t\t\t\t\t<img\n\t\t\t\t\t\tdecoding=\"async\"\n\t\t\t\t\t\talt=\"LinkedIn\"\n\t\t\t\t\t\tsrc=\"https:\/\/nodesmarket.com\/wp-content\/plugins\/site\/\/blocks\/person-card\/LinkedIn.png\"\n\t\t\t\t\t\twidth=\"2212\"\n\t\t\t\t\t\theight=\"540\"\n\t\t\t\t\t\tclass=\"wp-block-site-person-card__linked-in-img\"\n\t\t\t\t\t\/>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t<\/div>\n<\/div>\n\n<\/div>\n\n\n\n<div class=\"wp-block-site-person-card\" id=\"block-b13c66c60b93f3f09146d544625eadd3\">\n\n<div class=\"wp-block-site-person-card__inner\">\n\t<div class=\"wp-block-site-person-card__figure\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"684\" height=\"1024\" src=\"https:\/\/ds7yx6kld6i0w.cloudfront.net\/wp-content\/uploads\/2025\/01\/17135944\/close-up-684x1024.jpg\" class=\"wp-block-site-person-card__image\" alt=\"\" srcset=\"https:\/\/ds7yx6kld6i0w.cloudfront.net\/wp-content\/uploads\/2025\/01\/17135944\/close-up-684x1024.jpg 684w, https:\/\/ds7yx6kld6i0w.cloudfront.net\/wp-content\/uploads\/2025\/01\/17135944\/close-up-200x300.jpg 200w, https:\/\/ds7yx6kld6i0w.cloudfront.net\/wp-content\/uploads\/2025\/01\/17135944\/close-up-768x1149.jpg 768w, https:\/\/ds7yx6kld6i0w.cloudfront.net\/wp-content\/uploads\/2025\/01\/17135944\/close-up-1027x1536.jpg 1027w, https:\/\/ds7yx6kld6i0w.cloudfront.net\/wp-content\/uploads\/2025\/01\/17135944\/close-up.jpg 1080w\" sizes=\"auto, (max-width: 684px) 100vw, 684px\" \/>\t\t\t<\/div>\n\t<div class=\"wp-block-site-person-card__body\">\n\t\t<h3 class=\"wp-block-site-person-card__name\">\n\t\t\tJoachim Bj\u00f8rge\t\t<\/h3>\n\t\t<div class=\"wp-block-site-person-card__title\">\n\t\t\tSenior Frontend Developer\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"wp-block-site-person-card__linked-in\">\n\t\t\t\t<span class=\"wp-block-site-person-card__sr-only\">LinkedIn profil:<\/span>\n\t\t\t\t<a class=\"wp-block-site-person-card__linked-in-link\" href=\"https:\/\/www.linkedin.com\/in\/joachim-bj\u00f8rge-15335588\/\" target=\"_blank\" rel=\"nofollow\">\n\t\t\t\t\t<img\n\t\t\t\t\t\tdecoding=\"async\"\n\t\t\t\t\t\talt=\"LinkedIn\"\n\t\t\t\t\t\tsrc=\"https:\/\/nodesmarket.com\/wp-content\/plugins\/site\/\/blocks\/person-card\/LinkedIn.png\"\n\t\t\t\t\t\twidth=\"2212\"\n\t\t\t\t\t\theight=\"540\"\n\t\t\t\t\t\tclass=\"wp-block-site-person-card__linked-in-img\"\n\t\t\t\t\t\/>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t<\/div>\n<\/div>\n\n<\/div>\n\n\n\n<div class=\"wp-block-site-person-card\" id=\"block-f2d3dd96aba462c895336883ee4eb91f\">\n\n<div class=\"wp-block-site-person-card__inner\">\n\t<div class=\"wp-block-site-person-card__figure\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"866\" height=\"1024\" src=\"https:\/\/ds7yx6kld6i0w.cloudfront.net\/wp-content\/uploads\/2025\/01\/20134620\/Narve-866x1024.jpeg\" class=\"wp-block-site-person-card__image\" alt=\"\" srcset=\"https:\/\/ds7yx6kld6i0w.cloudfront.net\/wp-content\/uploads\/2025\/01\/20134620\/Narve-866x1024.jpeg 866w, https:\/\/ds7yx6kld6i0w.cloudfront.net\/wp-content\/uploads\/2025\/01\/20134620\/Narve-254x300.jpeg 254w, https:\/\/ds7yx6kld6i0w.cloudfront.net\/wp-content\/uploads\/2025\/01\/20134620\/Narve-768x909.jpeg 768w, https:\/\/ds7yx6kld6i0w.cloudfront.net\/wp-content\/uploads\/2025\/01\/20134620\/Narve-1298x1536.jpeg 1298w, https:\/\/ds7yx6kld6i0w.cloudfront.net\/wp-content\/uploads\/2025\/01\/20134620\/Narve-1731x2048.jpeg 1731w\" sizes=\"auto, (max-width: 866px) 100vw, 866px\" \/>\t\t\t<\/div>\n\t<div class=\"wp-block-site-person-card__body\">\n\t\t<h3 class=\"wp-block-site-person-card__name\">\n\t\t\tNarve S\u00e6tre\t\t<\/h3>\n\t\t<div class=\"wp-block-site-person-card__title\">\n\t\t\tSenior Backend Developer\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"wp-block-site-person-card__linked-in\">\n\t\t\t\t<span class=\"wp-block-site-person-card__sr-only\">LinkedIn profil:<\/span>\n\t\t\t\t<a class=\"wp-block-site-person-card__linked-in-link\" href=\"https:\/\/www.linkedin.com\/in\/narve-saetre\/\" target=\"_blank\" rel=\"nofollow\">\n\t\t\t\t\t<img\n\t\t\t\t\t\tdecoding=\"async\"\n\t\t\t\t\t\talt=\"LinkedIn\"\n\t\t\t\t\t\tsrc=\"https:\/\/nodesmarket.com\/wp-content\/plugins\/site\/\/blocks\/person-card\/LinkedIn.png\"\n\t\t\t\t\t\twidth=\"2212\"\n\t\t\t\t\t\theight=\"540\"\n\t\t\t\t\t\tclass=\"wp-block-site-person-card__linked-in-img\"\n\t\t\t\t\t\/>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t<\/div>\n<\/div>\n\n<\/div>\n\n\n\n<div class=\"wp-block-site-person-card\" id=\"block-3e3dba3a1d903e293502de97469624c0\">\n\n<div class=\"wp-block-site-person-card__inner\">\n\t<div class=\"wp-block-site-person-card__figure\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/ds7yx6kld6i0w.cloudfront.net\/wp-content\/uploads\/2025\/04\/22150505\/Christoffer-Ripegutu-768x1024.jpg\" class=\"wp-block-site-person-card__image\" alt=\"\" srcset=\"https:\/\/ds7yx6kld6i0w.cloudfront.net\/wp-content\/uploads\/2025\/04\/22150505\/Christoffer-Ripegutu-768x1024.jpg 768w, https:\/\/ds7yx6kld6i0w.cloudfront.net\/wp-content\/uploads\/2025\/04\/22150505\/Christoffer-Ripegutu-225x300.jpg 225w, https:\/\/ds7yx6kld6i0w.cloudfront.net\/wp-content\/uploads\/2025\/04\/22150505\/Christoffer-Ripegutu-1152x1536.jpg 1152w, https:\/\/ds7yx6kld6i0w.cloudfront.net\/wp-content\/uploads\/2025\/04\/22150505\/Christoffer-Ripegutu-1536x2048.jpg 1536w, https:\/\/ds7yx6kld6i0w.cloudfront.net\/wp-content\/uploads\/2025\/04\/22150505\/Christoffer-Ripegutu.jpg 1920w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/>\t\t\t<\/div>\n\t<div class=\"wp-block-site-person-card__body\">\n\t\t<h3 class=\"wp-block-site-person-card__name\">\n\t\t\tChristoffer Ripegutu\t\t<\/h3>\n\t\t<div class=\"wp-block-site-person-card__title\">\n\t\t\tJunior Project Manager\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"wp-block-site-person-card__linked-in\">\n\t\t\t\t<span class=\"wp-block-site-person-card__sr-only\">LinkedIn profil:<\/span>\n\t\t\t\t<a class=\"wp-block-site-person-card__linked-in-link\" href=\"https:\/\/www.linkedin.com\/in\/christoffer-ripegutu-a79867236\/\" target=\"_blank\" rel=\"nofollow\">\n\t\t\t\t\t<img\n\t\t\t\t\t\tdecoding=\"async\"\n\t\t\t\t\t\talt=\"LinkedIn\"\n\t\t\t\t\t\tsrc=\"https:\/\/nodesmarket.com\/wp-content\/plugins\/site\/\/blocks\/person-card\/LinkedIn.png\"\n\t\t\t\t\t\twidth=\"2212\"\n\t\t\t\t\t\theight=\"540\"\n\t\t\t\t\t\tclass=\"wp-block-site-person-card__linked-in-img\"\n\t\t\t\t\t\/>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t<\/div>\n<\/div>\n\n<\/div>\n\n\n\n<div class=\"wp-block-site-person-card\" id=\"block-64f17abfc7cb53108e4849243c7eeb8b\">\n\n<div class=\"wp-block-site-person-card__inner\">\n\t<div class=\"wp-block-site-person-card__figure\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"794\" height=\"1024\" src=\"https:\/\/ds7yx6kld6i0w.cloudfront.net\/wp-content\/uploads\/2025\/04\/30123343\/Frida-Johander-For-website-794x1024.jpg\" class=\"wp-block-site-person-card__image\" alt=\"\" srcset=\"https:\/\/ds7yx6kld6i0w.cloudfront.net\/wp-content\/uploads\/2025\/04\/30123343\/Frida-Johander-For-website-794x1024.jpg 794w, https:\/\/ds7yx6kld6i0w.cloudfront.net\/wp-content\/uploads\/2025\/04\/30123343\/Frida-Johander-For-website-233x300.jpg 233w, https:\/\/ds7yx6kld6i0w.cloudfront.net\/wp-content\/uploads\/2025\/04\/30123343\/Frida-Johander-For-website-768x991.jpg 768w, https:\/\/ds7yx6kld6i0w.cloudfront.net\/wp-content\/uploads\/2025\/04\/30123343\/Frida-Johander-For-website-1190x1536.jpg 1190w, https:\/\/ds7yx6kld6i0w.cloudfront.net\/wp-content\/uploads\/2025\/04\/30123343\/Frida-Johander-For-website.jpg 1416w\" sizes=\"auto, (max-width: 794px) 100vw, 794px\" \/>\t\t\t<\/div>\n\t<div class=\"wp-block-site-person-card__body\">\n\t\t<h3 class=\"wp-block-site-person-card__name\">\n\t\t\tFrida Johander\t\t<\/h3>\n\t\t<div class=\"wp-block-site-person-card__title\">\n\t\t\tJunior Project Manager\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"wp-block-site-person-card__linked-in\">\n\t\t\t\t<span class=\"wp-block-site-person-card__sr-only\">LinkedIn profil:<\/span>\n\t\t\t\t<a class=\"wp-block-site-person-card__linked-in-link\" href=\"https:\/\/www.linkedin.com\/in\/fridajohander\/\" target=\"_blank\" rel=\"nofollow\">\n\t\t\t\t\t<img\n\t\t\t\t\t\tdecoding=\"async\"\n\t\t\t\t\t\talt=\"LinkedIn\"\n\t\t\t\t\t\tsrc=\"https:\/\/nodesmarket.com\/wp-content\/plugins\/site\/\/blocks\/person-card\/LinkedIn.png\"\n\t\t\t\t\t\twidth=\"2212\"\n\t\t\t\t\t\theight=\"540\"\n\t\t\t\t\t\tclass=\"wp-block-site-person-card__linked-in-img\"\n\t\t\t\t\t\/>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t<\/div>\n<\/div>\n\n<\/div>\n\n\n\n<div class=\"wp-block-site-person-card\" id=\"block-0b2a83c8aa13a6a1901b20d274b39133\">\n\n<div class=\"wp-block-site-person-card__inner\">\n\t<div class=\"wp-block-site-person-card__figure\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/ds7yx6kld6i0w.cloudfront.net\/wp-content\/uploads\/2025\/10\/24125816\/4d52ef79-c921-4bdc-8848-4f0954d8cdfe-1024x1024.jpeg\" class=\"wp-block-site-person-card__image\" alt=\"\" srcset=\"https:\/\/ds7yx6kld6i0w.cloudfront.net\/wp-content\/uploads\/2025\/10\/24125816\/4d52ef79-c921-4bdc-8848-4f0954d8cdfe-1024x1024.jpeg 1024w, https:\/\/ds7yx6kld6i0w.cloudfront.net\/wp-content\/uploads\/2025\/10\/24125816\/4d52ef79-c921-4bdc-8848-4f0954d8cdfe-300x300.jpeg 300w, https:\/\/ds7yx6kld6i0w.cloudfront.net\/wp-content\/uploads\/2025\/10\/24125816\/4d52ef79-c921-4bdc-8848-4f0954d8cdfe-150x150.jpeg 150w, https:\/\/ds7yx6kld6i0w.cloudfront.net\/wp-content\/uploads\/2025\/10\/24125816\/4d52ef79-c921-4bdc-8848-4f0954d8cdfe-768x768.jpeg 768w, https:\/\/ds7yx6kld6i0w.cloudfront.net\/wp-content\/uploads\/2025\/10\/24125816\/4d52ef79-c921-4bdc-8848-4f0954d8cdfe.jpeg 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/>\t\t\t<\/div>\n\t<div class=\"wp-block-site-person-card__body\">\n\t\t<h3 class=\"wp-block-site-person-card__name\">\n\t\t\tKai Drange\t\t<\/h3>\n\t\t<div class=\"wp-block-site-person-card__title\">\n\t\t\tSenior Full-Stack Developer\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n<\/div>\n\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-group alignwide has-global-padding is-layout-constrained wp-block-group-is-layout-constrained\" style=\"padding-top:var(--wp--preset--spacing--60);padding-bottom:var(--wp--preset--spacing--60)\">\n<h2 class=\"wp-block-heading has-text-align-center\" style=\"margin-bottom:var(--wp--preset--spacing--50)\">Board of directors<\/h2>\n\n\n\n<div class=\"wp-block-group alignwide is-style-grid-cols-auto-fill\/min:17rem is-nowrap is-layout-flex wp-container-core-group-is-layout-9ad21752 wp-block-group-is-layout-flex\">\n<div class=\"wp-block-site-person-card\" id=\"block-211bbac526b01a16ece358af310d8043\">\n\n<div class=\"wp-block-site-person-card__inner\">\n\t<div class=\"wp-block-site-person-card__figure\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"881\" src=\"https:\/\/ds7yx6kld6i0w.cloudfront.net\/wp-content\/uploads\/2024\/12\/09083730\/Eivind-Tonnessen-e1733906713810-1024x881.jpg\" class=\"wp-block-site-person-card__image\" alt=\"\" srcset=\"https:\/\/ds7yx6kld6i0w.cloudfront.net\/wp-content\/uploads\/2024\/12\/09083730\/Eivind-Tonnessen-e1733906713810-1024x881.jpg 1024w, https:\/\/ds7yx6kld6i0w.cloudfront.net\/wp-content\/uploads\/2024\/12\/09083730\/Eivind-Tonnessen-e1733906713810-300x258.jpg 300w, https:\/\/ds7yx6kld6i0w.cloudfront.net\/wp-content\/uploads\/2024\/12\/09083730\/Eivind-Tonnessen-e1733906713810-768x661.jpg 768w, https:\/\/ds7yx6kld6i0w.cloudfront.net\/wp-content\/uploads\/2024\/12\/09083730\/Eivind-Tonnessen-e1733906713810-1536x1322.jpg 1536w, https:\/\/ds7yx6kld6i0w.cloudfront.net\/wp-content\/uploads\/2024\/12\/09083730\/Eivind-Tonnessen-e1733906713810-2048x1762.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/>\t\t\t<\/div>\n\t<div class=\"wp-block-site-person-card__body\">\n\t\t<h3 class=\"wp-block-site-person-card__name\">\n\t\t\tEivind T\u00f8nnessen\t\t<\/h3>\n\t\t<div class=\"wp-block-site-person-card__title\">\n\t\t\tChairman of the Board\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"wp-block-site-person-card__linked-in\">\n\t\t\t\t<span class=\"wp-block-site-person-card__sr-only\">LinkedIn profil:<\/span>\n\t\t\t\t<a class=\"wp-block-site-person-card__linked-in-link\" href=\"https:\/\/www.linkedin.com\/in\/eivind-t\u00f8nnessen-12978520\/\" target=\"_blank\" rel=\"nofollow\">\n\t\t\t\t\t<img\n\t\t\t\t\t\tdecoding=\"async\"\n\t\t\t\t\t\talt=\"LinkedIn\"\n\t\t\t\t\t\tsrc=\"https:\/\/nodesmarket.com\/wp-content\/plugins\/site\/\/blocks\/person-card\/LinkedIn.png\"\n\t\t\t\t\t\twidth=\"2212\"\n\t\t\t\t\t\theight=\"540\"\n\t\t\t\t\t\tclass=\"wp-block-site-person-card__linked-in-img\"\n\t\t\t\t\t\/>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t<\/div>\n<\/div>\n\n<\/div>\n\n\n\n<div class=\"wp-block-site-person-card\" id=\"block-d4f1a84a2d0c46d5f80472966466268d\">\n\n<div class=\"wp-block-site-person-card__inner\">\n\t<div class=\"wp-block-site-person-card__figure\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"938\" height=\"1024\" src=\"https:\/\/ds7yx6kld6i0w.cloudfront.net\/wp-content\/uploads\/2025\/08\/13144112\/IMG_1147-e1755089813403-938x1024.jpeg\" class=\"wp-block-site-person-card__image\" alt=\"\" srcset=\"https:\/\/ds7yx6kld6i0w.cloudfront.net\/wp-content\/uploads\/2025\/08\/13144112\/IMG_1147-e1755089813403-938x1024.jpeg 938w, https:\/\/ds7yx6kld6i0w.cloudfront.net\/wp-content\/uploads\/2025\/08\/13144112\/IMG_1147-e1755089813403-275x300.jpeg 275w, https:\/\/ds7yx6kld6i0w.cloudfront.net\/wp-content\/uploads\/2025\/08\/13144112\/IMG_1147-e1755089813403-768x839.jpeg 768w, https:\/\/ds7yx6kld6i0w.cloudfront.net\/wp-content\/uploads\/2025\/08\/13144112\/IMG_1147-e1755089813403.jpeg 1216w\" sizes=\"auto, (max-width: 938px) 100vw, 938px\" \/>\t\t\t<\/div>\n\t<div class=\"wp-block-site-person-card__body\">\n\t\t<h3 class=\"wp-block-site-person-card__name\">\n\t\t\tIngrid Lofnes\t\t<\/h3>\n\t\t<div class=\"wp-block-site-person-card__title\">\n\t\t\tBoard Member\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"wp-block-site-person-card__linked-in\">\n\t\t\t\t<span class=\"wp-block-site-person-card__sr-only\">LinkedIn profil:<\/span>\n\t\t\t\t<a class=\"wp-block-site-person-card__linked-in-link\" href=\"https:\/\/www.linkedin.com\/in\/ingrid-lofnes-b08519a8?trk=contact-info\" target=\"_blank\" rel=\"nofollow\">\n\t\t\t\t\t<img\n\t\t\t\t\t\tdecoding=\"async\"\n\t\t\t\t\t\talt=\"LinkedIn\"\n\t\t\t\t\t\tsrc=\"https:\/\/nodesmarket.com\/wp-content\/plugins\/site\/\/blocks\/person-card\/LinkedIn.png\"\n\t\t\t\t\t\twidth=\"2212\"\n\t\t\t\t\t\theight=\"540\"\n\t\t\t\t\t\tclass=\"wp-block-site-person-card__linked-in-img\"\n\t\t\t\t\t\/>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t<\/div>\n<\/div>\n\n<\/div>\n\n\n\n<div class=\"wp-block-site-person-card\" id=\"block-fc630a9d4d10230f30e950170784ee4f\">\n\n<div class=\"wp-block-site-person-card__inner\">\n\t<div class=\"wp-block-site-person-card__figure\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"884\" src=\"https:\/\/ds7yx6kld6i0w.cloudfront.net\/wp-content\/uploads\/2024\/12\/11094302\/Vidar-Kristoffer-Strat-e1733906651940-1024x884.jpg\" class=\"wp-block-site-person-card__image\" alt=\"\" srcset=\"https:\/\/ds7yx6kld6i0w.cloudfront.net\/wp-content\/uploads\/2024\/12\/11094302\/Vidar-Kristoffer-Strat-e1733906651940-1024x884.jpg 1024w, https:\/\/ds7yx6kld6i0w.cloudfront.net\/wp-content\/uploads\/2024\/12\/11094302\/Vidar-Kristoffer-Strat-e1733906651940-300x259.jpg 300w, https:\/\/ds7yx6kld6i0w.cloudfront.net\/wp-content\/uploads\/2024\/12\/11094302\/Vidar-Kristoffer-Strat-e1733906651940-768x663.jpg 768w, https:\/\/ds7yx6kld6i0w.cloudfront.net\/wp-content\/uploads\/2024\/12\/11094302\/Vidar-Kristoffer-Strat-e1733906651940-1536x1325.jpg 1536w, https:\/\/ds7yx6kld6i0w.cloudfront.net\/wp-content\/uploads\/2024\/12\/11094302\/Vidar-Kristoffer-Strat-e1733906651940-2048x1767.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/>\t\t\t<\/div>\n\t<div class=\"wp-block-site-person-card__body\">\n\t\t<h3 class=\"wp-block-site-person-card__name\">\n\t\t\tVidar Kristoffer Strat\t\t<\/h3>\n\t\t<div class=\"wp-block-site-person-card__title\">\n\t\t\tBoard Member\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"wp-block-site-person-card__linked-in\">\n\t\t\t\t<span class=\"wp-block-site-person-card__sr-only\">LinkedIn profil:<\/span>\n\t\t\t\t<a class=\"wp-block-site-person-card__linked-in-link\" href=\"https:\/\/www.linkedin.com\/in\/vidar-kristoffer-strat-6abb7410\/\" target=\"_blank\" rel=\"nofollow\">\n\t\t\t\t\t<img\n\t\t\t\t\t\tdecoding=\"async\"\n\t\t\t\t\t\talt=\"LinkedIn\"\n\t\t\t\t\t\tsrc=\"https:\/\/nodesmarket.com\/wp-content\/plugins\/site\/\/blocks\/person-card\/LinkedIn.png\"\n\t\t\t\t\t\twidth=\"2212\"\n\t\t\t\t\t\theight=\"540\"\n\t\t\t\t\t\tclass=\"wp-block-site-person-card__linked-in-img\"\n\t\t\t\t\t\/>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t<\/div>\n<\/div>\n\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-group alignwide has-global-padding is-layout-constrained wp-block-group-is-layout-constrained\" style=\"padding-top:var(--wp--preset--spacing--60);padding-bottom:var(--wp--preset--spacing--60)\">\n<h2 class=\"wp-block-heading has-text-align-center\" style=\"margin-bottom:var(--wp--preset--spacing--50)\">Address<\/h2>\n\n\n\n<div class=\"wp-block-group alignwide is-style-dark-mode has-global-padding is-layout-constrained wp-block-group-is-layout-constrained\">\n<div class=\"wp-block-columns alignwide is-layout-flex wp-container-core-columns-is-layout-873e7f5b wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<div class=\"align wp-block-site-map\" id=\"block-9bea9de41a356b7be075479203792d1a\">\n\n\t<div\n\t\tclass=\"wp-block-site-map__map-canvas\"\n\t\tdata-lat=\"59.911771086662\"\n\t\tdata-lng=\"10.638325152887\"\n\t\tdata-zoom=\"16\"\n\t><\/div>\n\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"padding-top:var(--wp--preset--spacing--60);padding-right:var(--wp--preset--spacing--70);padding-bottom:var(--wp--preset--spacing--60);padding-left:var(--wp--preset--spacing--70);flex-basis:512px\">\n<div class=\"wp-block-group has-global-padding is-content-justification-left is-layout-constrained wp-container-core-group-is-layout-b7900d69 wp-block-group-is-layout-constrained\">\n<div class=\"wp-block-group has-global-padding is-layout-constrained wp-block-group-is-layout-constrained\">\n<h2 class=\"wp-block-heading\">NODES AS<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Strandveien 13<br>1366 Lysaker<br>NORWAY<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a class=\"absconditus\" data-absconditus-a=\"bsav\" data-absconditus-b=\"ABQRFznexrg.pbz\" href=\"#\"><span data-absconditus-placeholder=\"mtroconSOm.efiDEaNk@\"><\/span><\/a><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Meet the Team NODES\u2122 has a highly experienced team with diverse backgrounds in information technology, electricity markets, regulation, grid operation,&hellip;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"content-type":"","inline_featured_image":false,"footnotes":""},"class_list":["post-187","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Meet the Team - NODESmarket<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nodesmarket.com\/meet-the-team\/\" \/>\n<meta property=\"og:locale\" content=\"nb_NO\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Meet the Team - NODESmarket\" \/>\n<meta property=\"og:description\" content=\"Meet the Team NODES\u2122 has a highly experienced team with diverse backgrounds in information technology, electricity markets, regulation, grid operation,&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nodesmarket.com\/meet-the-team\/\" \/>\n<meta property=\"og:site_name\" content=\"NODESmarket\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-23T10:16:57+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@NODESmarket\" \/>\n<meta name=\"twitter:label1\" content=\"Ansl. lesetid\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minutt\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/nodesmarket.com\\\/meet-the-team\\\/\",\"url\":\"https:\\\/\\\/nodesmarket.com\\\/meet-the-team\\\/\",\"name\":\"Meet the Team - NODESmarket\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nodesmarket.com\\\/#website\"},\"datePublished\":\"2024-01-22T10:51:57+00:00\",\"dateModified\":\"2026-06-23T10:16:57+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/nodesmarket.com\\\/meet-the-team\\\/#breadcrumb\"},\"inLanguage\":\"nb-NO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/nodesmarket.com\\\/meet-the-team\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/nodesmarket.com\\\/meet-the-team\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/nodesmarket.com\\\/no\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Meet the Team\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/nodesmarket.com\\\/#website\",\"url\":\"https:\\\/\\\/nodesmarket.com\\\/\",\"name\":\"NODESmarket\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/nodesmarket.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/nodesmarket.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nb-NO\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/nodesmarket.com\\\/#organization\",\"name\":\"NODES AS\",\"url\":\"https:\\\/\\\/nodesmarket.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nb-NO\",\"@id\":\"https:\\\/\\\/nodesmarket.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/ds7yx6kld6i0w.cloudfront.net\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/24085756\\\/NODES_logopack-RGB_green.svg\",\"contentUrl\":\"https:\\\/\\\/ds7yx6kld6i0w.cloudfront.net\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/24085756\\\/NODES_logopack-RGB_green.svg\",\"caption\":\"NODES AS\"},\"image\":{\"@id\":\"https:\\\/\\\/nodesmarket.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/NODESmarket\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/nodesmarket\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@nodesmarket\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Meet the Team - NODESmarket","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nodesmarket.com\/meet-the-team\/","og_locale":"nb_NO","og_type":"article","og_title":"Meet the Team - NODESmarket","og_description":"Meet the Team NODES\u2122 has a highly experienced team with diverse backgrounds in information technology, electricity markets, regulation, grid operation,&hellip;","og_url":"https:\/\/nodesmarket.com\/meet-the-team\/","og_site_name":"NODESmarket","article_modified_time":"2026-06-23T10:16:57+00:00","twitter_card":"summary_large_image","twitter_site":"@NODESmarket","twitter_misc":{"Ansl. lesetid":"1 minutt"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/nodesmarket.com\/meet-the-team\/","url":"https:\/\/nodesmarket.com\/meet-the-team\/","name":"Meet the Team - NODESmarket","isPartOf":{"@id":"https:\/\/nodesmarket.com\/#website"},"datePublished":"2024-01-22T10:51:57+00:00","dateModified":"2026-06-23T10:16:57+00:00","breadcrumb":{"@id":"https:\/\/nodesmarket.com\/meet-the-team\/#breadcrumb"},"inLanguage":"nb-NO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nodesmarket.com\/meet-the-team\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/nodesmarket.com\/meet-the-team\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/nodesmarket.com\/no\/"},{"@type":"ListItem","position":2,"name":"Meet the Team"}]},{"@type":"WebSite","@id":"https:\/\/nodesmarket.com\/#website","url":"https:\/\/nodesmarket.com\/","name":"NODESmarket","description":"","publisher":{"@id":"https:\/\/nodesmarket.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nodesmarket.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nb-NO"},{"@type":"Organization","@id":"https:\/\/nodesmarket.com\/#organization","name":"NODES AS","url":"https:\/\/nodesmarket.com\/","logo":{"@type":"ImageObject","inLanguage":"nb-NO","@id":"https:\/\/nodesmarket.com\/#\/schema\/logo\/image\/","url":"https:\/\/ds7yx6kld6i0w.cloudfront.net\/wp-content\/uploads\/2024\/01\/24085756\/NODES_logopack-RGB_green.svg","contentUrl":"https:\/\/ds7yx6kld6i0w.cloudfront.net\/wp-content\/uploads\/2024\/01\/24085756\/NODES_logopack-RGB_green.svg","caption":"NODES AS"},"image":{"@id":"https:\/\/nodesmarket.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/NODESmarket","https:\/\/www.linkedin.com\/company\/nodesmarket\/","https:\/\/www.youtube.com\/@nodesmarket"]}]}},"_links":{"self":[{"href":"https:\/\/nodesmarket.com\/no\/wp-json\/wp\/v2\/pages\/187","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nodesmarket.com\/no\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/nodesmarket.com\/no\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/nodesmarket.com\/no\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/nodesmarket.com\/no\/wp-json\/wp\/v2\/comments?post=187"}],"version-history":[{"count":104,"href":"https:\/\/nodesmarket.com\/no\/wp-json\/wp\/v2\/pages\/187\/revisions"}],"predecessor-version":[{"id":11935,"href":"https:\/\/nodesmarket.com\/no\/wp-json\/wp\/v2\/pages\/187\/revisions\/11935"}],"wp:attachment":[{"href":"https:\/\/nodesmarket.com\/no\/wp-json\/wp\/v2\/media?parent=187"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}